{"id":2831,"date":"2023-01-05T08:39:25","date_gmt":"2023-01-05T07:39:25","guid":{"rendered":"https:\/\/willynacho.com\/crispy-maiskolf\/"},"modified":"2023-09-13T14:22:25","modified_gmt":"2023-09-13T12:22:25","slug":"crispy-maiskolf","status":"publish","type":"post","link":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/","title":{"rendered":"Crispy Corn Cob"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin_phone=&#8221;-30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; constrain_group_2=&#8221;yes&#8221; constrain_group_6=&#8221;yes&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style steadysets-icon-users2 extra-color-1\"><\/i> <\/div><div class=\"iwt-text\"> <strong>2 to 3 people<\/strong> <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style steadysets-icon-clock extra-color-1\"><\/i> <\/div><div class=\"iwt-text\"> <b>Preparation time: 30 min<\/b> <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;iconsmind&#8221; text=&#8221;Back to overview&#8221; icon_iconsmind=&#8221;iconsmind-Bulleted-List&#8221; url=&#8221;https:\/\/willynacho.com\/recepten\/&#8221;][\/vc_column_inner][\/vc_row_inner][image_with_animation image_url=&#8221;2111&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;-75&#8243; top_margin_phone=&#8221;-60&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1659&#8243; image_size=&#8221;medium_large&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; constrain_group_6=&#8221;yes&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_left_phone=&#8221;20%&#8221; margin_right_phone=&#8221;20%&#8221;][vc_column_text el_class=&#8221;recept-intro&#8221;]Corn is very popular in Mexico and is also often eaten from the barbecue. We understand why Mexico loves corn after tasting the roasted corn cobs on a stick![\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_phone=&#8221;20%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;20%&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;steps&#8221; row_name=&#8221;Sign Up Steps&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#edb202&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Ingredients&#8221; font_container=&#8221;tag:h2|font_size:25|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-check\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"extra-color-3\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li><strong><a href=\"https:\/\/willynacho.com\/en\/producten\/tortilla-chips-chili\/\" target=\"_blank\" rel=\"noopener\">100 gr. Willy Nacho Tortilla Chips Chili<span class=\"Apple-converted-space\"> <\/span><\/a><\/strong><\/li>\n<li><a href=\"https:\/\/willynacho.com\/en\/producten\/cheese-dip\/\" target=\"_blank\" rel=\"noopener\"><strong>200 gr. Willy Nacho Cheese dip<\/strong><\/a><\/li>\n<li>3 Precooked corn cobs<\/li>\n<li>4 gr. Paprika<\/li>\n<li>Salt<\/li>\n<\/ul>\n<p>Mango Chutney*<\/p>\n<ul>\n<li>1 Mango (diced)<\/li>\n<li>1 Red pepper (finely chopped)<\/li>\n<li>50 gr. Sugar<\/li>\n<\/ul>\n <\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;80&#8243;][vc_custom_heading text=&#8221;Supplies&#8221; font_container=&#8221;tag:h2|font_size:25|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-check\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"extra-color-3\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li>Oven resistant dish<\/li>\n<li>Sticks<\/li>\n<li>Plate<\/li>\n<li>Pan<\/li>\n<li>Cutting board<\/li>\n<li>Knife<\/li>\n<li>Hand blender<\/li>\n<\/ul>\n <\/div>[\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;What to do \/ como trabajo:&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23edb202&#8243; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_icon_list animate=&#8221;true&#8221; color=&#8221;Extra-Color-2&#8243; direction=&#8221;vertical&#8221; icon_size=&#8221;medium&#8221; icon_style=&#8221;border&#8221;][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1672904580380-3&#8243; header=&#8221;Step 1&#8243; text=&#8221;Cut the corn cobs in half, then insert the sticks into the cobs. Put some salt on top. Put the corn cobs in the oven at 200 degrees for 10 to 15 minutes.&#8221; tab_id=&#8221;1672904580380-8&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1672904580393-7&#8243; header=&#8221;Step 2&#8243; text=&#8221;Meanwhile, heat the Cheesedip in a saucepan. Swirl the corn cobs through the Cheesedip.&#8221; tab_id=&#8221;1672904580393-1&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1672904580403-1&#8243; header=&#8221;Step 3&#8243; text=&#8221;Grab a plate with the crunchy pieces of tortilla chips. Roll the corn cobs with Cheesedip through the chips, making sure they are well coated.&#8221; tab_id=&#8221;1672904580404-3&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1672904580415-0&#8243; header=&#8221;Step 4&#8243; text=&#8221;Sprinkle with some smoked paprika and serve with the mango chutney!&#8221; tab_id=&#8221;1672904580415-9&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1672904580426-8&#8243; tab_id=&#8221;1672904580426-0&#8243; icon_fontawesome=&#8221;fa fa-star-o&#8221; header=&#8221;Mango Chutney&#8221; text=&#8221;Put the diced mango in a pan with the chopped red pepper and sugar. Let this simmer until soft. Then gently puree to make a chutney.&#8221;][\/nectar_icon_list_item][\/nectar_icon_list][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;See more recipes with these ingredients:&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Corn is very popular in Mexico and is also often eaten from the barbecue. We understand why Mexico loves corn after tasting the roasted corn cobs on a stick!<\/p>\n","protected":false},"author":1,"featured_media":2482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65,67],"tags":[43,41],"class_list":["post-2831","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gluten-free","category-vegetarian","tag-willy-nacho-cheese-dip-en","tag-willy-nacho-tortilla-chips-chili-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crispy Corn Cob &#8902; willynacho.com<\/title>\n<meta name=\"description\" content=\"We understand why Mexico loves corn! Feast on the corn on the cob, coated in cheese dip with a crunch of tortilla chips!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crispy Corn Cob &#8902; willynacho.com\" \/>\n<meta property=\"og:description\" content=\"We understand why Mexico loves corn! Feast on the corn on the cob, coated in cheese dip with a crunch of tortilla chips!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/\" \/>\n<meta property=\"og:site_name\" content=\"willynacho.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/willynacho\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-05T07:39:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-13T12:22:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/11\/Crunchy-Maiskolf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Willy Nacho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Willy Nacho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/\"},\"author\":{\"name\":\"Willy Nacho\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#\\\/schema\\\/person\\\/9fb132723a53bb6bab11af0dd9186692\"},\"headline\":\"Crispy Corn Cob\",\"datePublished\":\"2023-01-05T07:39:25+00:00\",\"dateModified\":\"2023-09-13T12:22:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/\"},\"wordCount\":1788,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Crunchy-Maiskolf.jpg\",\"keywords\":[\"Willy Nacho Cheese Dip\",\"Willy Nacho Tortilla Chips Chili\"],\"articleSection\":[\"Gluten-free\",\"Vegetarian\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/\",\"url\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/\",\"name\":\"Crispy Corn Cob &#8902; willynacho.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Crunchy-Maiskolf.jpg\",\"datePublished\":\"2023-01-05T07:39:25+00:00\",\"dateModified\":\"2023-09-13T12:22:25+00:00\",\"description\":\"We understand why Mexico loves corn! Feast on the corn on the cob, coated in cheese dip with a crunch of tortilla chips!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Crunchy-Maiskolf.jpg\",\"contentUrl\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Crunchy-Maiskolf.jpg\",\"width\":2000,\"height\":1334,\"caption\":\"Ma\u00efs is zeer geliefd in Mexico en wordt ook vaak gegeten van de barbecue. Wij snappen waarom Mexico dol is op ma\u00efs na het proeven van de geroosterde ma\u00efskolven op een stokje!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/dishes\\\/gluten-free\\\/crispy-maiskolf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/willynacho.com\\\/en\\\/willy-nacho-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crispy Corn Cob\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/willynacho.com\\\/en\\\/\",\"name\":\"willynacho.com\",\"description\":\"Best Nacho's in Town\",\"publisher\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/willynacho.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#organization\",\"name\":\"Willy Nacho\",\"url\":\"https:\\\/\\\/willynacho.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WillyNacho-Logo-500x400px.png\",\"contentUrl\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WillyNacho-Logo-500x400px.png\",\"width\":500,\"height\":400,\"caption\":\"Willy Nacho\"},\"image\":{\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/willynacho\",\"https:\\\/\\\/www.instagram.com\\\/willynachos\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/willynachos\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/en\\\/#\\\/schema\\\/person\\\/9fb132723a53bb6bab11af0dd9186692\",\"name\":\"Willy Nacho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Willy-Nacho-Willy-200x200px-100x100.png\",\"url\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Willy-Nacho-Willy-200x200px-100x100.png\",\"contentUrl\":\"https:\\\/\\\/willynacho.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Willy-Nacho-Willy-200x200px-100x100.png\",\"caption\":\"Willy Nacho\"},\"sameAs\":[\"https:\\\/\\\/willynacho.com\"],\"url\":\"https:\\\/\\\/willynacho.com\\\/en\\\/author\\\/nachos4life\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crispy Corn Cob &#8902; willynacho.com","description":"We understand why Mexico loves corn! Feast on the corn on the cob, coated in cheese dip with a crunch of tortilla chips!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/","og_locale":"en_US","og_type":"article","og_title":"Crispy Corn Cob &#8902; willynacho.com","og_description":"We understand why Mexico loves corn! Feast on the corn on the cob, coated in cheese dip with a crunch of tortilla chips!","og_url":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/","og_site_name":"willynacho.com","article_publisher":"https:\/\/www.facebook.com\/willynacho","article_published_time":"2023-01-05T07:39:25+00:00","article_modified_time":"2023-09-13T12:22:25+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/11\/Crunchy-Maiskolf.jpg","type":"image\/jpeg"}],"author":"Willy Nacho","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Willy Nacho","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#article","isPartOf":{"@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/"},"author":{"name":"Willy Nacho","@id":"https:\/\/willynacho.com\/en\/#\/schema\/person\/9fb132723a53bb6bab11af0dd9186692"},"headline":"Crispy Corn Cob","datePublished":"2023-01-05T07:39:25+00:00","dateModified":"2023-09-13T12:22:25+00:00","mainEntityOfPage":{"@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/"},"wordCount":1788,"commentCount":0,"publisher":{"@id":"https:\/\/willynacho.com\/en\/#organization"},"image":{"@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#primaryimage"},"thumbnailUrl":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/11\/Crunchy-Maiskolf.jpg","keywords":["Willy Nacho Cheese Dip","Willy Nacho Tortilla Chips Chili"],"articleSection":["Gluten-free","Vegetarian"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/","url":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/","name":"Crispy Corn Cob &#8902; willynacho.com","isPartOf":{"@id":"https:\/\/willynacho.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#primaryimage"},"image":{"@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#primaryimage"},"thumbnailUrl":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/11\/Crunchy-Maiskolf.jpg","datePublished":"2023-01-05T07:39:25+00:00","dateModified":"2023-09-13T12:22:25+00:00","description":"We understand why Mexico loves corn! Feast on the corn on the cob, coated in cheese dip with a crunch of tortilla chips!","breadcrumb":{"@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#primaryimage","url":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/11\/Crunchy-Maiskolf.jpg","contentUrl":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/11\/Crunchy-Maiskolf.jpg","width":2000,"height":1334,"caption":"Ma\u00efs is zeer geliefd in Mexico en wordt ook vaak gegeten van de barbecue. Wij snappen waarom Mexico dol is op ma\u00efs na het proeven van de geroosterde ma\u00efskolven op een stokje!"},{"@type":"BreadcrumbList","@id":"https:\/\/willynacho.com\/en\/dishes\/gluten-free\/crispy-maiskolf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/willynacho.com\/en\/willy-nacho-home\/"},{"@type":"ListItem","position":2,"name":"Crispy Corn Cob"}]},{"@type":"WebSite","@id":"https:\/\/willynacho.com\/en\/#website","url":"https:\/\/willynacho.com\/en\/","name":"willynacho.com","description":"Best Nacho's in Town","publisher":{"@id":"https:\/\/willynacho.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/willynacho.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/willynacho.com\/en\/#organization","name":"Willy Nacho","url":"https:\/\/willynacho.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/willynacho.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/05\/WillyNacho-Logo-500x400px.png","contentUrl":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/05\/WillyNacho-Logo-500x400px.png","width":500,"height":400,"caption":"Willy Nacho"},"image":{"@id":"https:\/\/willynacho.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/willynacho","https:\/\/www.instagram.com\/willynachos\/","https:\/\/nl.pinterest.com\/willynachos\/"]},{"@type":"Person","@id":"https:\/\/willynacho.com\/en\/#\/schema\/person\/9fb132723a53bb6bab11af0dd9186692","name":"Willy Nacho","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/08\/Willy-Nacho-Willy-200x200px-100x100.png","url":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/08\/Willy-Nacho-Willy-200x200px-100x100.png","contentUrl":"https:\/\/willynacho.com\/wp-content\/uploads\/2022\/08\/Willy-Nacho-Willy-200x200px-100x100.png","caption":"Willy Nacho"},"sameAs":["https:\/\/willynacho.com"],"url":"https:\/\/willynacho.com\/en\/author\/nachos4life\/"}]}},"_links":{"self":[{"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/posts\/2831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/comments?post=2831"}],"version-history":[{"count":18,"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/posts\/2831\/revisions"}],"predecessor-version":[{"id":3171,"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/posts\/2831\/revisions\/3171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/media\/2482"}],"wp:attachment":[{"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/media?parent=2831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/categories?post=2831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/willynacho.com\/en\/wp-json\/wp\/v2\/tags?post=2831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}